{"id":2058,"date":"2021-01-20T11:20:07","date_gmt":"2021-01-20T10:20:07","guid":{"rendered":"https:\/\/primate.si\/v2\/?post_type=portfolio&#038;p=2058"},"modified":"2022-10-14T19:18:58","modified_gmt":"2022-10-14T17:18:58","slug":"senidah-sladjana","status":"publish","type":"portfolio","link":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/","title":{"rendered":"Senidah &#8211; Sla\u0111ana"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;0&#8243; back_color=&#8221;color-jevc&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;2&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;-5&#8243; shift_y_down_fixed=&#8221;yes&#8221; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; align_mobile=&#8221;align_center_mobile&#8221; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; limit_content=&#8221;&#8221; el_class=&#8221;evolve_with_us&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_custom_heading heading_semantic=&#8221;h1&#8243; text_font=&#8221;font-902532&#8243; text_size=&#8221;h1&#8243; sub_lead=&#8221;yes&#8221; sub_reduced=&#8221;yes&#8221; subheading=&#8221;Senidah&#8221; uncode_shortcode_id=&#8221;182656&#8243;]<\/p>\n<h1><strong>SLA\u0110ANA<\/strong><\/h1>\n<p>[\/vc_custom_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner row_inner_height_percent=&#8221;0&#8243; force_width_grid=&#8221;yes&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; limit_content=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_single_image media=&#8221;2256&#8243; media_width_percent=&#8221;100&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;5&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; border_color=&#8221;color-jevc&#8221; border_style=&#8221;solid&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; css=&#8221;.vc_custom_1613652918255{margin-top: 60px !important;border-top-width: 40px !important;padding-top: 40px !important;}&#8221;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;3&#8243; back_color=&#8221;color-210407&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; css=&#8221;.vc_custom_1613659566790{border-top-width: 50px !important;padding-top: 10px !important;}&#8221; el_class=&#8221;textblock&#8221;][vc_custom_heading sub_reduced=&#8221;yes&#8221;][\/vc_custom_heading][vc_column_text css=&#8221;.vc_custom_1665767935586{padding-top: 2% !important;}&#8221; uncode_shortcode_id=&#8221;147500&#8243;]<\/p>\n<h2><strong><span class=\"font-567931\" style=\"color: #000000;\">CREW<\/span><\/strong><\/h2>\n<p>[\/vc_column_text][vc_column_text text_lead=&#8221;yes&#8221; el_class=&#8221;textblock&#8221;]<span style=\"color: #000000;\">Director: <strong>\u017diga Radulj\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">DOP: <strong>Tilen Ba\u010dar\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">Producer: <strong>\u017diga Radulj<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Camera: <strong>Nejc Miljak \u00a0 \u00a0 \u00a0<\/strong>PA<\/span><span style=\"color: #000000;\">: <strong>Filip \u0110uri\u0107\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">Edit: <strong>\u017diga Radulj, Nejc Miljak<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Color Grade: <strong>Tilen Ba\u010dar\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">VFX: <strong>\u017diga Radulj\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">Photo: <strong>Matic Krem\u017ear<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Styling: <strong>Nina \u0160u\u0161njara\u00a0 \u00a0 \u00a0 <\/strong><\/span><span style=\"color: #000000;\">MUA: <\/span><strong><span style=\"color: #000000;\">Maja \u0160u\u0161njara<\/span>\u00a0 \u00a0 \u00a0<\/strong><span style=\"color: #000000;\">Hairstyle: <strong>Jane Go\u010dev<\/strong><\/span>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;0&#8243; back_color=&#8221;color-jevc&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;2&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2412,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"portfolio_category":[6],"class_list":["post-2058","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-mic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve\" \/>\n<meta property=\"og:description\" content=\"[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;0&#8243; back_color=&#8221;color-jevc&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;2&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/\" \/>\n<meta property=\"og:site_name\" content=\"Wild Ideas Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Primate.si\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-14T17:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/primate.si\/wp-content\/uploads\/2021\/01\/SENIDAH-.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/\",\"url\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/\",\"name\":\"Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/primate.si\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/SENIDAH-.webp\",\"datePublished\":\"2021-01-20T10:20:07+00:00\",\"dateModified\":\"2022-10-14T17:18:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/primate.si\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/SENIDAH-.webp\",\"contentUrl\":\"https:\\\/\\\/primate.si\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/SENIDAH-.webp\",\"width\":1500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/senidah-sladjana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/primate.si\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/primate.si\\\/en\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senidah &#8211; Sla\u0111ana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/primate.si\\\/en\\\/\",\"name\":\"PRIMATE - Wild Ideas Evolve\",\"description\":\"PRIMATE\",\"publisher\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/primate.si\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#organization\",\"name\":\"PRIMATE\",\"url\":\"https:\\\/\\\/primate.si\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/primate.si\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/PRIMATE_logo_single_black.png\",\"contentUrl\":\"https:\\\/\\\/primate.si\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/PRIMATE_logo_single_black.png\",\"width\":2218,\"height\":301,\"caption\":\"PRIMATE\"},\"image\":{\"@id\":\"https:\\\/\\\/primate.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Primate.si\",\"https:\\\/\\\/www.instagram.com\\\/primate.si\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/primatesi\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/","og_locale":"en_US","og_type":"article","og_title":"Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve","og_description":"[vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;0&#8243; back_color=&#8221;color-jevc&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;2&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]","og_url":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/","og_site_name":"Wild Ideas Evolve","article_publisher":"https:\/\/www.facebook.com\/Primate.si","article_modified_time":"2022-10-14T17:18:58+00:00","og_image":[{"width":1500,"height":750,"url":"https:\/\/primate.si\/wp-content\/uploads\/2021\/01\/SENIDAH-.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/","url":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/","name":"Senidah - Sla\u0111ana &#8211; Wild Ideas Evolve","isPartOf":{"@id":"https:\/\/primate.si\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/#primaryimage"},"image":{"@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/#primaryimage"},"thumbnailUrl":"https:\/\/primate.si\/wp-content\/uploads\/2021\/01\/SENIDAH-.webp","datePublished":"2021-01-20T10:20:07+00:00","dateModified":"2022-10-14T17:18:58+00:00","breadcrumb":{"@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/#primaryimage","url":"https:\/\/primate.si\/wp-content\/uploads\/2021\/01\/SENIDAH-.webp","contentUrl":"https:\/\/primate.si\/wp-content\/uploads\/2021\/01\/SENIDAH-.webp","width":1500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/primate.si\/en\/portfolio\/senidah-sladjana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/primate.si\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/primate.si\/en\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Senidah &#8211; Sla\u0111ana"}]},{"@type":"WebSite","@id":"https:\/\/primate.si\/en\/#website","url":"https:\/\/primate.si\/en\/","name":"PRIMATE - Wild Ideas Evolve","description":"PRIMATE","publisher":{"@id":"https:\/\/primate.si\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/primate.si\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/primate.si\/en\/#organization","name":"PRIMATE","url":"https:\/\/primate.si\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/primate.si\/en\/#\/schema\/logo\/image\/","url":"https:\/\/primate.si\/wp-content\/uploads\/2021\/07\/PRIMATE_logo_single_black.png","contentUrl":"https:\/\/primate.si\/wp-content\/uploads\/2021\/07\/PRIMATE_logo_single_black.png","width":2218,"height":301,"caption":"PRIMATE"},"image":{"@id":"https:\/\/primate.si\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Primate.si","https:\/\/www.instagram.com\/primate.si","https:\/\/www.linkedin.com\/company\/primatesi\/"]}]}},"_links":{"self":[{"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/portfolio\/2058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/comments?post=2058"}],"version-history":[{"count":13,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/portfolio\/2058\/revisions"}],"predecessor-version":[{"id":7439,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/portfolio\/2058\/revisions\/7439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/media\/2412"}],"wp:attachment":[{"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/media?parent=2058"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/primate.si\/en\/wp-json\/wp\/v2\/portfolio_category?post=2058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}